{"id":120,"date":"2011-03-10T13:13:53","date_gmt":"2011-03-10T19:13:53","guid":{"rendered":"https:\/\/www.parrinst.com\/?page_id=120"},"modified":"2020-01-22T14:24:37","modified_gmt":"2020-01-22T20:24:37","slug":"series-5100-glass-reactors","status":"publish","type":"page","link":"https:\/\/www.parrinst.com\/de\/products\/stirred-reactors\/series-5100-glass-reactors\/","title":{"rendered":"Serie 5100 Glasreaktoren, 160-1500 ml"},"content":{"rendered":"\n\t\t\t<div id='120-1' class='gallery gallery-120 gallery-columns-3 gallery-size-medium' itemscope itemtype='http:\/\/schema.org\/ImageGallery'>\n\t\t\t\t<div class='gallery-row gallery-col-3 gallery-clear'>\n\t\t\t\t\t<figure class='gallery-item col-3' itemprop='associatedMedia' itemscope itemtype='http:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t<div class='gallery-icon portrait'><a href=\"https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2011\/03\/5100_shield-on.jpg?ssl=1\" itemprop=\"contentURL\"><img loading=\"lazy\" decoding=\"async\" width=\"215\" height=\"300\" src=\"https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2011\/03\/5100_shield-on.jpg?fit=215%2C300&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"5100 Reactor shown with protective shield securely latched in place.\" srcset=\"https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2011\/03\/5100_shield-on.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2011\/03\/5100_shield-on.jpg?resize=107%2C150&amp;ssl=1 107w, https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2011\/03\/5100_shield-on.jpg?resize=215%2C300&amp;ssl=1 215w\" sizes=\"auto, (max-width: 215px) 100vw, 215px\" itemprop=\"thumbnail\" \/><\/a><\/div>\n\t\t\t\t\t<\/figure>\n\t\t\t\t\t<figure class='gallery-item col-3' itemprop='associatedMedia' itemscope itemtype='http:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t<div class='gallery-icon landscape'><a href=\"https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2018\/01\/5100_cover-off_600x600.jpg?ssl=1\" itemprop=\"contentURL\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2018\/01\/5100_cover-off_600x600.jpg?fit=300%2C300&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"5111 Bench Top Reactor, 1000 mL, Fixed Head, Glass Jacketed Vessel.\" srcset=\"https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2018\/01\/5100_cover-off_600x600.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2018\/01\/5100_cover-off_600x600.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2018\/01\/5100_cover-off_600x600.jpg?resize=300%2C300&amp;ssl=1 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" itemprop=\"thumbnail\" \/><\/a><\/div>\n\t\t\t\t\t<\/figure>\n\t\t\t\t\t<figure class='gallery-item col-3' itemprop='associatedMedia' itemscope itemtype='http:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t<div class='gallery-icon portrait'><a href=\"https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2011\/03\/5100_detail.jpg?ssl=1\" itemprop=\"contentURL\"><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"300\" src=\"https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2011\/03\/5100_detail.jpg?fit=247%2C300&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"300 mL Glass Vessel with latched Split Ring and 6-blade impeller.\" srcset=\"https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2011\/03\/5100_detail.jpg?w=433&amp;ssl=1 433w, https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2011\/03\/5100_detail.jpg?resize=247%2C300&amp;ssl=1 247w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" itemprop=\"thumbnail\" \/><\/a><\/div>\n\t\t\t\t\t<\/figure>\n\t\t\t\t<\/div>\n\t\t\t<\/div><!-- .gallery -->\n\n<p><strong>Die Serie 5100 Niedrigdruckreaktoren wird auf Anwenderwunsch, um:<br \/>\n<\/strong><\/p>\n<ol>\n<li>Ein System f\u00fcr die Durchf\u00fchrung von Reaktionen \u00e4hnlich wie jene in dem schon seit vielen Jahren erh\u00e4ltlichen Hydrierapparat, allerdings mit einer R\u00fchrfunktion f\u00fcr eine bessere Skalierbarkeit, h\u00f6here Temperaturen und Arbeitsdr\u00fccke sowie weiterreichende Reaktorregelungen und Ausstattungen, bereitzustellen.<\/li>\n<li>Die Vorg\u00e4nge im Reaktionsgef\u00e4\u00df direkt zu beobachten und die Vermischung, Farb\u00e4nderungen oder Phasen\u00fcberg\u00e4nge zu verfolgen.<\/li>\n<li>Reaktoren mit einfacher Bedienung bei moderaten Dr\u00fccken sowie der Eignung f\u00fcr Reaktionen, die einen Korrosionsschutz erfordern, anzubieten.<\/li>\n<\/ol>\n<h3>Bequeme und einfache Abdichtung mit einem O-Ring und dem Split-Ring Verschlusssystem<\/h3>\n<p><strong>Parr hat ein neues Verschlusssystem mit O-Ring entwickelt<\/strong>, das den Anforderungen an diese einzigartige Glas-auf-Metall Dichtstelle gerecht wird und einfach zu handhaben ist. Eine Gleitringdichtung wird mit dem bekannten und bew\u00e4hrten Parr Split-Ring-System verwendet. Daf\u00fcr wurde eine spezielle Nut gestaltet, die es erlaubt, dass der O-Ring im Reaktorkopf bleibt, wenn der Reaktor ge\u00f6ffnet wird. Um die chemische Kompatibilit\u00e4t mit den Edukten, Produkten und L\u00f6sungsmitteln zu gew\u00e4hrleisten, ist eine gro\u00dfe Bandbreite an O-Ring-Materialien erh\u00e4ltlich.<\/p>\n<table class=\"nostyle\">\n<tbody>\n<tr>\n<td>\n<figure id=\"attachment_5440\" aria-describedby=\"caption-attachment-5440\" style=\"width: 300px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2011\/03\/Split-ring_glass.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-5440 size-medium\" src=\"https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2011\/03\/Split-ring_glass.jpg?resize=300%2C126&#038;ssl=1\" alt=\"Split Ring for Glass Reactors\" width=\"300\" height=\"126\" srcset=\"https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2011\/03\/Split-ring_glass.jpg?resize=300%2C126&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2011\/03\/Split-ring_glass.jpg?w=600&amp;ssl=1 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-5440\" class=\"wp-caption-text\">Split-Ring f\u00fcr Glasreaktoren<\/figcaption><\/figure><\/td>\n<td>\n<figure id=\"attachment_12012\" aria-describedby=\"caption-attachment-12012\" style=\"width: 299px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2011\/03\/Split-Ring-for-Metal_c-clamp-1.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-12012\" src=\"https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2011\/03\/Split-Ring-for-Metal_c-clamp-1.jpg?resize=299%2C126&#038;ssl=1\" alt=\"Split-Ring f\u00fcr Metallreaktoren\" width=\"299\" height=\"126\" srcset=\"https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2011\/03\/Split-Ring-for-Metal_c-clamp-1.jpg?resize=300%2C127&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2011\/03\/Split-Ring-for-Metal_c-clamp-1.jpg?resize=356%2C150&amp;ssl=1 356w, https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2011\/03\/Split-Ring-for-Metal_c-clamp-1.jpg?w=600&amp;ssl=1 600w\" sizes=\"auto, (max-width: 299px) 100vw, 299px\" \/><\/a><figcaption id=\"caption-attachment-12012\" class=\"wp-caption-text\">Split-Ring f\u00fcr Metallreaktoren<\/figcaption><\/figure><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Der Split-Ring f\u00fcr den Glasbeh\u00e4lter ist mit Kunststoffkissen f\u00fcr Hochtemperaturen belegt, damit der Glasbeh\u00e4lter nicht in direkten Kontakt mit dem Metall-Split-Ring kommt. Sechs Abdichtschrauben werden handfest angezogen, um die n\u00f6tige Dichtkraft auf den O-Ring auszu\u00fcben. Der Split-Ring schlie\u00dft mit Schnappriegel und sorgt f\u00fcr einen formschl\u00fcssigen und sicheren Verschluss.<\/p>\n<p>Der alternative Metallzylinder nutzt einen anderen Split-Ring, der den h\u00f6heren Arbeitsdr\u00fccken der Metalldruckbeh\u00e4lter standh\u00e4lt.<\/p>\n<h3>Kr\u00e4ftiges R\u00fchren durch Magnetantrieb mit hohem Drehmoment<\/h3>\n<h3><\/h3>\n<p><strong>Diese Reaktoren sind mit dem Parr Magnetantrieb ausgestattet<\/strong> und erlauben ein st\u00f6rungsfreies internes R\u00fchren. Diese Antriebe wurden so ausgelegt und getestet, dass sie \u00fcblicherweise 2000 Arbeitsstunden ohne Wartung laufen k\u00f6nnen.<\/p>\n<h3>Internes R\u00fchrwerk<\/h3>\n<p><strong>Das serienm\u00e4\u00dfige, interne R\u00fchrwerk f\u00fcr diese Druckbeh\u00e4lter ist ein turbinenf\u00f6rmiger Impeller.<\/strong> Diese Impeller sind so ausgef\u00fchrt, dass sie f\u00fcr eine gute axiale Durchmischung sorgen, um alle Feststoffe in einer Suspension zu halten und eine gute Gasverteilung innerhalb der fl\u00fcssigen Phasen zu gew\u00e4hrleisten.<\/p>\n<p>Ein Gaseintragsr\u00fchrer ist als alternativer R\u00fchrer f\u00fcr alle Anwender erh\u00e4ltlich, die eine Gasr\u00fcckf\u00fchrung vom Kopfbereich des Reaktors durch die fl\u00fcssige Phase w\u00fcnschen.<\/p>\n<h3>Serienm\u00e4\u00dfige Reaktoraustattung<\/h3>\n<p>Der Kopf jedes Glasreaktors ist ausgestattet mit:<\/p>\n<ul>\n<li>Manometer, 3,5 Zoll Durchmesser, Messbereich 0-14 bar und 0-200 psi<\/li>\n<li>Gasauslassventil<\/li>\n<li>Gaseinlassventil<\/li>\n<li>Probenentnahmeventil<\/li>\n<li>Internes Thermoelement<\/li>\n<li>K\u00fchlschlange \u2013 serienm\u00e4\u00dfig bei 300 ml bis 1,5 l<\/li>\n<li>Internes R\u00fchrwerk mit Magnetantrieb<\/li>\n<li>K\u00f6pfe, die f\u00fcr den Gebrauch mit Glaszylindern vorgesehen sind, werden mit federvorgespannten Druckbegrenzungsventilen ausgestattet, die im Bereich 3,5 \u2013 10 bar (50 -150 psi) eingestellt werden k\u00f6nnen<\/li>\n<li>Alle K\u00f6pfe werden mit einer Berstscheibe ausgestattet, die f\u00fcr 1000 psi zugelassen ist<\/li>\n<li>Interne Materialien sind aus Edelstahl T316 mit einer PTFE-Beschichtung<\/li>\n<\/ul>\n<h3>Konstruktionsmaterial<\/h3>\n<p>Diese Reaktoren sind eine Kombination aus Reaktionsbeh\u00e4ltern aus Glas mit Beh\u00e4lterk\u00f6pfen aus Metall, internem R\u00fchrer, Tauchrohr, Thermoh\u00fclse, K\u00fchlschlange sowie externen Ventilen und Anschl\u00fcssen oder alternativ\u00a0 komplett aus Metall.<\/p>\n<p>Das \u00fcbliche Konstruktionsmaterial f\u00fcr den Kopf ist Edelstahl T316, die Einbauten sind mit PTFE \u00fcberzogen. Sowohl der Kopf als auch alle Einbauten k\u00f6nnen aus anderen Materialien hergestellt werden. Konstruktionsmaterialien finden Sie unter 5100 Bestellschl\u00fcssel.<\/p>\n<h3>Gr\u00f6\u00dfe<\/h3>\n<p><strong>Die Reaktoren der Serie 5100 k\u00f6nnen einfach zwischen den Gr\u00f6\u00dfen<\/strong> 160, 300, 450 und 600 ml umger\u00fcstet werden, indem man den Zylinder und die internen Teile austauscht. Nach demselben Prinzip lassen sich auch die Gr\u00f6\u00dfen 1 l und 1,5 l untereinander tauschen. W\u00e4hrend der 160-600 ml Stand nicht f\u00fcr die gr\u00f6\u00dferen 1 l und 1,5 l Beh\u00e4lter umger\u00fcstet werden kann, ist es allerdings m\u00f6glich den gr\u00f6\u00dferen Stand f\u00fcr die Aufnahme von 160-600 ml Druckbeh\u00e4ltern anzupassen. Falls Sie planen den Reaktor zu einem sp\u00e4teren Zeitpunkt umzur\u00fcsten, stellen Sie sicher, dass Sie einen Stand passend zum gr\u00f6\u00dften Beh\u00e4lter bestellen, damit die Schutzscheibe und der Rahmen sp\u00e4ter nicht ausgetauscht werden m\u00fcssen.<\/p>\n<h3>Heizung und Temperaturregelung<\/h3>\n<p><strong>Diese Reaktoren sind entweder mit einfachen Glasgef\u00e4\u00dfen oder mit Gef\u00e4\u00dfen mit Doppelmantel erh\u00e4ltlich,<\/strong> diese werden entweder mit einem beweglichen Heizmantel oder einen Thermostaten geheizt. Im Allgemeinen werden Glasbeh\u00e4lter mit einem Thermostaten beheizt, um so den Vorteil der Transparenz zu erhalten. F\u00fcr manche Anwendungen ist es vielleicht nicht n\u00f6tig, w\u00e4hrend der Reaktion zu heizen,\u00a0 oder der Anwender bevorzugt einen beweglichen Heizmantel, wenn bei h\u00f6heren Temperaturen gearbeitet werden muss. Obwohl die Transparenz bei Metallzylindern keine Rolle spielt, w\u00e4hlen die meisten Nutzer dieselbe Heizmethode f\u00fcr den Metallzylinder wie f\u00fcr den Glaszylinder, sodass sie f\u00fcr beide Arten dieselben Heiz- und Regelsysteme verwenden k\u00f6nnen.<\/p>\n<p>Anwender, die einen Thermostaten benutzen, der \u00fcber eine eigene Temperaturregelung verf\u00fcgt, ben\u00f6tigen keinen 4848 Controller, da kein Heizmantel n\u00f6tig ist. Diesen Anwendern reicht eine einfache Motorsteuerung. Die meisten handels\u00fcblichen Laborthermostaten eignen sich f\u00fcr die Beheizung dieser kleinen Gef\u00e4\u00dfen. F\u00fcr die Gef\u00e4\u00dfe ohne Thermostaten sind bewegliche elektrische Heizmantel verf\u00fcgbar, die f\u00fcr 115 bzw. 230 VAC ausgelegt sind.<\/p>\n<h3>4848 Controller<\/h3>\n<p><strong>Der Parr Controller 4848 verf\u00fcgt \u00fcber eine PC-Kommunikation<\/strong> zu allen Funktionen, welche im Controller verbaut sind. Der Controller 4848 bietet eine PID Regelung mit Auto-Tune, eine Rampen und Stufen Programmierung, separate Heiz- und K\u00fchlregelschleifen, eine Geschwindigkeitsregelung f\u00fcr den R\u00fchrmotor, die M\u00f6glichkeit der halben und vollen Heizleistung, ein Abschaltrelais mit R\u00fccksetzung f\u00fcr \u00dcberhitzungsschutz, Erweiterungsmodule f\u00fcr Drehzahlmesser, Druck und Hochtemperaturalarm. Wenn es gew\u00fcnscht wird, dass der Reaktor automatisch ein vorher festgelegtes Temperaturprofil verfolgt, kann der Controller 4848 auch mit dieser Funktion ausgestattet werden. Diese Controller regeln dann den elektrischen Heizmantel, k\u00f6nnen aber nicht mit dem Thermostaten verbunden werden.<\/p>\n<h3>A2110E Motor-Controller<\/h3>\n<p>Anwender, die einen Thermostaten mit den Doppelmantel-Gef\u00e4\u00dfen verwenden, ben\u00f6tigen nur die Motor-Steuerung A2110E zu Einstellung und Regelung der R\u00fchrgeschwindigkeiten.<\/p>\n<h3>R\u00fchrmotoren<\/h3>\n<p>F\u00fcr die Reaktorserie 5100 gibt es die Wahlm\u00f6glichkeit zwischen drei verschiedenen Motoren:<\/p>\n<ul>\n<li>Der serienm\u00e4\u00dfige Motor verf\u00fcgt \u00fcber 90 Watt und eine variable Geschwindigkeit.<\/li>\n<li>Die \u00fcblichen R\u00fchrgeschwindigkeiten liegen zwischen 0 und 1700 Umdrehungen pro Minute. Die zweistufige Antriebsscheibe liefert bei Auswahl der kleineren Scheibe ein doppeltes Drehmoment bei halbierter Drehzahl.<\/li>\n<li>Ein explosionsgesch\u00fctzer Motor mit 180 Watt ist erh\u00e4ltlich. Dieser Motor verf\u00fcgt ebenso \u00fcber variable Drehzahlen und den gleichen Drehzahlbereich wie der Standard-Motor.<\/li>\n<li>Ein Druckluftmotor ist lieferbar f\u00fcr alle, die die zus\u00e4tzliche Sicherheit eines nicht-elektrischen Motors ben\u00f6tigen und eine variable Druckluftquelle zur Verf\u00fcgung haben.<\/li>\n<\/ul>\n<h3>5110 Umbaus\u00e4tze: Glas in Metall oder Metall in Glas<\/h3>\n<p>Die Reaktoren der Serie 5100 k\u00f6nnen einfach von einem Glas- zu einem \u00a0Metallbeh\u00e4lter umgebaut werden. Die Umbaus\u00e4tze enthalten Zylinder, Verschluss, Manometer und Sicherheitseinrichtungen f\u00fcr das umzur\u00fcstende System. Eine Heizung ist in den Umbaus\u00e4tzen nicht enthalten.<\/p>\n<table class=\"OrderingGuide\">\n<tbody>\n<tr>\n<td class=\"OrderingGuide-DarkGreen\" colspan=\"4\">5110 und 5120 Umbaus\u00e4tze<\/td>\n<\/tr>\n<tr>\n<td colspan=\"4\"><strong>Glas in Metall<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"18%\"><strong>Katalognummer<\/strong><\/td>\n<td width=\"18%\"><strong>Gr\u00f6\u00dfe ml<\/strong><\/td>\n<td width=\"32%\"><strong>Umgebaut von<br \/>\n<\/strong><\/td>\n<td width=\"32%\"><strong>Umgebaut in<br \/>\n<\/strong><\/td>\n<\/tr>\n<tr>\n<td>5110A<\/td>\n<td>300<\/td>\n<td>glasummantelt<\/td>\n<td>metallummantelt<\/td>\n<\/tr>\n<tr class=\"OrderingGuide-LightGreen\">\n<td>5110B<\/td>\n<td>300<\/td>\n<td>Glas<\/td>\n<td>Metall<\/td>\n<\/tr>\n<tr>\n<td>5110C<\/td>\n<td>450<\/td>\n<td>glasummantelt<\/td>\n<td>metallummantelt<\/td>\n<\/tr>\n<tr class=\"OrderingGuide-LightGreen\">\n<td>5110D<\/td>\n<td>450<\/td>\n<td>Glas<\/td>\n<td>Metall<\/td>\n<\/tr>\n<tr>\n<td>5110E<\/td>\n<td>600<\/td>\n<td>glasummantelt<\/td>\n<td>metallummantelt<\/td>\n<\/tr>\n<tr class=\"OrderingGuide-LightGreen\">\n<td>5110F<\/td>\n<td>600<\/td>\n<td>Glas<\/td>\n<td>Metall<\/td>\n<\/tr>\n<tr>\n<td>5110M<\/td>\n<td>215<\/td>\n<td>glasummantelt<\/td>\n<td>metallummantelt<\/td>\n<\/tr>\n<tr class=\"OrderingGuide-LightGreen\">\n<td>5110N<\/td>\n<td>160<\/td>\n<td>Glas<\/td>\n<td>Metall<\/td>\n<\/tr>\n<tr>\n<td>5120A<\/td>\n<td>1000<\/td>\n<td>glasummantelt<\/td>\n<td>metallummantelt<\/td>\n<\/tr>\n<tr class=\"OrderingGuide-LightGreen\">\n<td>5120B<\/td>\n<td>1000<\/td>\n<td>Glas<\/td>\n<td>Metall<\/td>\n<\/tr>\n<tr>\n<td>5120C<\/td>\n<td>1500<\/td>\n<td>glasummantelt<\/td>\n<td>metallummantelt<\/td>\n<\/tr>\n<tr class=\"OrderingGuide-LightGreen\">\n<td>5120D<\/td>\n<td>1500<\/td>\n<td>Glas<\/td>\n<td>Metall<\/td>\n<\/tr>\n<tr>\n<td colspan=\"4\"><\/td>\n<\/tr>\n<tr>\n<td colspan=\"4\"><strong>Metall in Glas<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>Katalognummer<\/strong><\/td>\n<td><strong>Gr\u00f6\u00dfe ml<\/strong><\/td>\n<td><strong>Umgebaut von<\/strong><\/td>\n<td><strong>Umgebaut in<\/strong><\/td>\n<\/tr>\n<tr>\n<td>5110G<\/td>\n<td>300<\/td>\n<td>metallummantelt<\/td>\n<td>glasummantelt<\/td>\n<\/tr>\n<tr class=\"OrderingGuide-LightGreen\">\n<td>5110H<\/td>\n<td>300<\/td>\n<td>Metall<\/td>\n<td>Glas<\/td>\n<\/tr>\n<tr>\n<td>5110I<\/td>\n<td>450<\/td>\n<td>metallummantelt<\/td>\n<td>glasummantelt<\/td>\n<\/tr>\n<tr class=\"OrderingGuide-LightGreen\">\n<td>5110J<\/td>\n<td>450<\/td>\n<td>Metall<\/td>\n<td>Glas<\/td>\n<\/tr>\n<tr>\n<td>5110K<\/td>\n<td>600<\/td>\n<td>metallummantelt<\/td>\n<td>glasummantelt<\/td>\n<\/tr>\n<tr class=\"OrderingGuide-LightGreen\">\n<td>5110L<\/td>\n<td>600<\/td>\n<td>Metall<\/td>\n<td>Glas<\/td>\n<\/tr>\n<tr>\n<td>5110P<\/td>\n<td>215<\/td>\n<td>metallummantelt<\/td>\n<td>glasummantelt<\/td>\n<\/tr>\n<tr class=\"OrderingGuide-LightGreen\">\n<td>5110Q<\/td>\n<td>160<\/td>\n<td>Metall<\/td>\n<td>Glas<\/td>\n<\/tr>\n<tr>\n<td>5120E<\/td>\n<td>1000<\/td>\n<td>metallummantelt<\/td>\n<td>glasummantelt<\/td>\n<\/tr>\n<tr class=\"OrderingGuide-LightGreen\">\n<td>5120F<\/td>\n<td>1000<\/td>\n<td>Metall<\/td>\n<td>Glas<\/td>\n<\/tr>\n<tr>\n<td>5120G<\/td>\n<td>1500<\/td>\n<td>metallummantelt<\/td>\n<td>glasummantelt<\/td>\n<\/tr>\n<tr class=\"OrderingGuide-LightGreen\">\n<td>5120H<\/td>\n<td>1500<\/td>\n<td>Metall<\/td>\n<td>Glas<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<hr \/>\n<div>\n<h3>Glas Unter Druck<\/h3>\n<\/div>\n<div>\n<p>In den vergangenen siebzig Jahren, seit Parr Ger\u00e4te herstellt, die mit Glasdruckbeh\u00e4ltern und -Flaschen ausgestattet sind, haben wir folgende wichtige Dinge gelernt:<\/p>\n<ol>\n<li><strong>Reaktionen unter Hochdruck und -temperatur<\/strong> k\u00f6nnen nur sicher durchgef\u00fchrt werden, wenn der Anwender sich \u00fcber die potentiellen Gefahren bewusst ist, die dadurch entstehen, wenn ein Glasbeh\u00e4lter unter Druck zerbirst.<\/li>\n<li><strong>Die Druckbeh\u00e4lterkonstruktion ist entscheidend.<\/strong> Glasbeh\u00e4lter sollten abgerundete Abs\u00e4tze haben, korrekt ausgek\u00fchlt sind, eine gepolsterte Abst\u00fctzung haben und es sollten Vorkehrungen f\u00fcr unterschiedliche W\u00e4rmeausdehnungskoeffizienten getroffen werden. Ebenso viel Aufmerksamkeit sollte einer ad\u00e4quaten Dicke, einer sorgf\u00e4ltigen Konstruktion und Inspektion sowie den Testl\u00e4ufen entgegen gebracht werden. Alle Glasdruckbeh\u00e4lter, die in diesen Reaktoren Verwendung finden, sind bei mindestens 15 bar (225 psi) getestet worden.<\/li>\n<li><strong>Eine sorgf\u00e4ltige Wartung ist ebenso wichtig<\/strong> f\u00fcr einen sicheren Betrieb der Glasbeh\u00e4lter. Kratzer auf Metallbeh\u00e4ltern sind nur von kosmetischer Natur. Hingegen erh\u00f6hen Kratzer auf Glasbeh\u00e4ltern die Spannungen im Glas betr\u00e4chtlich und k\u00f6nnen so die strukturelle Integrit\u00e4t des Druckbeh\u00e4lters zerst\u00f6ren. Bei der Handhabung und dem Reinigen dieser Beh\u00e4lter muss man gro\u00dfe Vorsicht walten lassen.<\/li>\n<li><strong>Der Anwender eines Glasreaktors muss intensiv geschult sein<\/strong>, um die potentiellen Gefahren zu erkennen und um sicher zu stellen, dass geeignete Sicherheitsma\u00dfnahmen jederzeit vorhanden und betriebsbereit sind.<\/li>\n<\/ol>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Serie 5100 Niedrigdruckreaktoren wird auf Anwenderwunsch, um: Ein System f\u00fcr die Durchf\u00fchrung von Reaktionen \u00e4hnlich wie jene in dem schon seit vielen Jahren erh\u00e4ltlichen Hydrierapparat, allerdings mit einer R\u00fchrfunktion f\u00fcr eine bessere Skalierbarkeit, h\u00f6here Temperaturen und Arbeitsdr\u00fccke sowie weiterreichende Reaktorregelungen und Ausstattungen, bereitzustellen. Die Vorg\u00e4nge im Reaktionsgef\u00e4\u00df direkt zu beobachten und die Vermischung, Farb\u00e4nderungen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":36873,"parent":47,"menu_order":9,"comment_status":"closed","ping_status":"closed","template":"product-wide-strirred-filter.php","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-120","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Serie 5100 Glasreaktoren, 160-1500 ml - Parr Instrument GmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.parrinst.com\/de\/products\/stirred-reactors\/series-5100-glass-reactors\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Serie 5100 Glasreaktoren, 160-1500 ml - Parr Instrument GmbH\" \/>\n<meta property=\"og:description\" content=\"Die Serie 5100 Niedrigdruckreaktoren wird auf Anwenderwunsch, um: Ein System f\u00fcr die Durchf\u00fchrung von Reaktionen \u00e4hnlich wie jene in dem schon seit vielen Jahren erh\u00e4ltlichen Hydrierapparat, allerdings mit einer R\u00fchrfunktion f\u00fcr eine bessere Skalierbarkeit, h\u00f6here Temperaturen und Arbeitsdr\u00fccke sowie weiterreichende Reaktorregelungen und Ausstattungen, bereitzustellen. Die Vorg\u00e4nge im Reaktionsgef\u00e4\u00df direkt zu beobachten und die Vermischung, Farb\u00e4nderungen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.parrinst.com\/de\/products\/stirred-reactors\/series-5100-glass-reactors\/\" \/>\n<meta property=\"og:site_name\" content=\"Parr Instrument GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-22T20:24:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.parrinst.com\/de\/files\/2017\/12\/parr_banner_stirred3_secondary.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2200\" \/>\n\t<meta property=\"og:image:height\" content=\"399\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.parrinst.com\\\/de\\\/products\\\/stirred-reactors\\\/series-5100-glass-reactors\\\/\",\"url\":\"https:\\\/\\\/www.parrinst.com\\\/de\\\/products\\\/stirred-reactors\\\/series-5100-glass-reactors\\\/\",\"name\":\"Serie 5100 Glasreaktoren, 160-1500 ml - Parr Instrument GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.parrinst.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.parrinst.com\\\/de\\\/products\\\/stirred-reactors\\\/series-5100-glass-reactors\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.parrinst.com\\\/de\\\/products\\\/stirred-reactors\\\/series-5100-glass-reactors\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.parrinst.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/12\\\/parr_banner_stirred3_secondary.jpg?fit=2200%2C399&ssl=1\",\"datePublished\":\"2011-03-10T19:13:53+00:00\",\"dateModified\":\"2020-01-22T20:24:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.parrinst.com\\\/de\\\/products\\\/stirred-reactors\\\/series-5100-glass-reactors\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.parrinst.com\\\/de\\\/products\\\/stirred-reactors\\\/series-5100-glass-reactors\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.parrinst.com\\\/de\\\/products\\\/stirred-reactors\\\/series-5100-glass-reactors\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.parrinst.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/12\\\/parr_banner_stirred3_secondary.jpg?fit=2200%2C399&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.parrinst.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/12\\\/parr_banner_stirred3_secondary.jpg?fit=2200%2C399&ssl=1\",\"width\":2200,\"height\":399},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.parrinst.com\\\/de\\\/products\\\/stirred-reactors\\\/series-5100-glass-reactors\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.parrinst.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.parrinst.com\\\/de\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ger\u00fchrte Reaktoren\",\"item\":\"https:\\\/\\\/www.parrinst.com\\\/de\\\/products\\\/stirred-reactors\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Serie 5100 Glasreaktoren, 160-1500 ml\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.parrinst.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.parrinst.com\\\/de\\\/\",\"name\":\"Parr Instrument GmbH\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.parrinst.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Serie 5100 Glasreaktoren, 160-1500 ml - Parr Instrument GmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.parrinst.com\/de\/products\/stirred-reactors\/series-5100-glass-reactors\/","og_locale":"en_US","og_type":"article","og_title":"Serie 5100 Glasreaktoren, 160-1500 ml - Parr Instrument GmbH","og_description":"Die Serie 5100 Niedrigdruckreaktoren wird auf Anwenderwunsch, um: Ein System f\u00fcr die Durchf\u00fchrung von Reaktionen \u00e4hnlich wie jene in dem schon seit vielen Jahren erh\u00e4ltlichen Hydrierapparat, allerdings mit einer R\u00fchrfunktion f\u00fcr eine bessere Skalierbarkeit, h\u00f6here Temperaturen und Arbeitsdr\u00fccke sowie weiterreichende Reaktorregelungen und Ausstattungen, bereitzustellen. Die Vorg\u00e4nge im Reaktionsgef\u00e4\u00df direkt zu beobachten und die Vermischung, Farb\u00e4nderungen [&hellip;]","og_url":"https:\/\/www.parrinst.com\/de\/products\/stirred-reactors\/series-5100-glass-reactors\/","og_site_name":"Parr Instrument GmbH","article_modified_time":"2020-01-22T20:24:37+00:00","og_image":[{"width":2200,"height":399,"url":"https:\/\/www.parrinst.com\/de\/files\/2017\/12\/parr_banner_stirred3_secondary.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.parrinst.com\/de\/products\/stirred-reactors\/series-5100-glass-reactors\/","url":"https:\/\/www.parrinst.com\/de\/products\/stirred-reactors\/series-5100-glass-reactors\/","name":"Serie 5100 Glasreaktoren, 160-1500 ml - Parr Instrument GmbH","isPartOf":{"@id":"https:\/\/www.parrinst.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.parrinst.com\/de\/products\/stirred-reactors\/series-5100-glass-reactors\/#primaryimage"},"image":{"@id":"https:\/\/www.parrinst.com\/de\/products\/stirred-reactors\/series-5100-glass-reactors\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2017\/12\/parr_banner_stirred3_secondary.jpg?fit=2200%2C399&ssl=1","datePublished":"2011-03-10T19:13:53+00:00","dateModified":"2020-01-22T20:24:37+00:00","breadcrumb":{"@id":"https:\/\/www.parrinst.com\/de\/products\/stirred-reactors\/series-5100-glass-reactors\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.parrinst.com\/de\/products\/stirred-reactors\/series-5100-glass-reactors\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.parrinst.com\/de\/products\/stirred-reactors\/series-5100-glass-reactors\/#primaryimage","url":"https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2017\/12\/parr_banner_stirred3_secondary.jpg?fit=2200%2C399&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.parrinst.com\/de\/wp-content\/uploads\/sites\/6\/2017\/12\/parr_banner_stirred3_secondary.jpg?fit=2200%2C399&ssl=1","width":2200,"height":399},{"@type":"BreadcrumbList","@id":"https:\/\/www.parrinst.com\/de\/products\/stirred-reactors\/series-5100-glass-reactors\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.parrinst.com\/de\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.parrinst.com\/de\/products\/"},{"@type":"ListItem","position":3,"name":"Ger\u00fchrte Reaktoren","item":"https:\/\/www.parrinst.com\/de\/products\/stirred-reactors\/"},{"@type":"ListItem","position":4,"name":"Serie 5100 Glasreaktoren, 160-1500 ml"}]},{"@type":"WebSite","@id":"https:\/\/www.parrinst.com\/de\/#website","url":"https:\/\/www.parrinst.com\/de\/","name":"Parr Instrument GmbH","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.parrinst.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.parrinst.com\/de\/wp-json\/wp\/v2\/pages\/120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.parrinst.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.parrinst.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.parrinst.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.parrinst.com\/de\/wp-json\/wp\/v2\/comments?post=120"}],"version-history":[{"count":8,"href":"https:\/\/www.parrinst.com\/de\/wp-json\/wp\/v2\/pages\/120\/revisions"}],"predecessor-version":[{"id":40292,"href":"https:\/\/www.parrinst.com\/de\/wp-json\/wp\/v2\/pages\/120\/revisions\/40292"}],"up":[{"embeddable":true,"href":"https:\/\/www.parrinst.com\/de\/wp-json\/wp\/v2\/pages\/47"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.parrinst.com\/de\/wp-json\/wp\/v2\/media\/36873"}],"wp:attachment":[{"href":"https:\/\/www.parrinst.com\/de\/wp-json\/wp\/v2\/media?parent=120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}